{"id":21739,"date":"2022-07-27T13:42:10","date_gmt":"2022-07-27T17:42:10","guid":{"rendered":"https:\/\/staging.wcwc.ca\/news-fr\/analyste-de-la-qualite-de-leau-ceu-18\/"},"modified":"2026-05-05T15:18:51","modified_gmt":"2026-05-05T19:18:51","slug":"analyste-de-la-qualite-de-leau-ceu-18","status":"publish","type":"post","link":"https:\/\/wcwc.ca\/fr\/coursecatalog-fr\/analyste-de-la-qualite-de-leau-ceu-18\/","title":{"rendered":"Analyste de la qualit\u00e9 de l&#8217;eau &#8211; UFC: 1,8"},"content":{"rendered":"<div>\n<h2>Aper\u00e7u du cours<\/h2>\n<\/div>\n<div>\n<p>Ce cours de trois jours donnera aux participants une vue d&#8217;ensemble du r\u00f4le d&#8217;un analyste de la qualit\u00e9 de l&#8217;eau, depuis la compr\u00e9hension des exigences r\u00e9glementaires et des principes de base de la chimie et de la microbiologie jusqu&#8217;\u00e0 l&#8217;utilisation de formules et de calculs de base.<\/p>\n<p>Les domaines d&#8217;\u00e9tude sont les suivants<\/p>\n<ul>\n<li>L\u00e9gislation sur l&#8217;eau potable<\/li>\n<li>Comp\u00e9tences math\u00e9matiques de base (principes, syst\u00e8me m\u00e9trique et conversion, formules et calculs)<\/li>\n<li>Principes de chimie<\/li>\n<li>\u00c9chantillonnage et surveillance<\/li>\n<li>\u00c9quipement et s\u00e9curit\u00e9 des laboratoires<\/li>\n<li>Param\u00e8tres analytiques, techniques et importance du processus (exigences du r\u00e8glement 170\/03)<\/li>\n<li>Temp\u00e9rature, pH, turbidit\u00e9, duret\u00e9<\/li>\n<li>Solides dissous et r\u00e9sidus de chlore<\/li>\n<li>Param\u00e8tres microbiologiques<\/li>\n<\/ul>\n<\/div>\n<div>\n<h2>Public cible<\/h2>\n<p>Ce cours est destin\u00e9 aux personnes qui souhaitent travailler dans un environnement de laboratoire en mettant l&#8217;accent sur la compr\u00e9hension des param\u00e8tres physiques, chimiques et microbiologiques relatifs \u00e0 la qualit\u00e9 de l&#8217;eau dans les usines. Des connaissances de base en chimie (pH, alcalinit\u00e9, duret\u00e9, conductivit\u00e9, turbidit\u00e9, etc.<\/p>\n<p><span style=\"color: revert; font-size: 28.8325px; font-weight: bold; letter-spacing: -0.720813px;\">M\u00e9thodes de livraison possibles<\/span><\/p>\n<\/div>\n<div>\n<p>Salle de classe, sur place<\/p>\n<\/div>\n<p><span class=\"gt3_font-weight\" style=\"font-weight: 600;\">Visitez notre <a href=\"https:\/\/wcwc.ca\/fr\/formation\/cours\/\">page d&#8217;inscription aux cours<\/a> pour consulter notre calendrier !<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aper\u00e7u du cours Ce cours de trois jours donnera aux participants une vue d&#8217;ensemble du r\u00f4le d&#8217;un analyste de la qualit\u00e9 de l&#8217;eau, depuis &#8230;<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[585],"tags":[],"course-type":[],"province":[1016],"class_list":["post-21739","post","type-post","status-publish","format-standard","hentry","category-coursecatalog-fr","province-on"],"acf":[],"_links":{"self":[{"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/posts\/21739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/comments?post=21739"}],"version-history":[{"count":5,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/posts\/21739\/revisions"}],"predecessor-version":[{"id":26798,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/posts\/21739\/revisions\/26798"}],"wp:attachment":[{"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/media?parent=21739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/categories?post=21739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/tags?post=21739"},{"taxonomy":"course-type","embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/course-type?post=21739"},{"taxonomy":"province","embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/province?post=21739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}