{"id":21761,"date":"2022-07-27T12:06:18","date_gmt":"2022-07-27T16:06:18","guid":{"rendered":"https:\/\/staging.wcwc.ca\/news-fr\/maintenir-la-stabilite-de-leau-dans-les-reseaux-de-distribution-ceu-0-7\/"},"modified":"2026-05-05T14:46:31","modified_gmt":"2026-05-05T18:46:31","slug":"maintenir-la-stabilite-de-leau-dans-les-reseaux-de-distribution-ceu-0-7","status":"publish","type":"post","link":"https:\/\/wcwc.ca\/fr\/coursecatalog-fr\/maintenir-la-stabilite-de-leau-dans-les-reseaux-de-distribution-ceu-0-7\/","title":{"rendered":"Gestion la stabilit\u00e9 de l\u2019eau dans les r\u00e9seaux de distribution &#8211; UFC: 0,7"},"content":{"rendered":"<div>\n<div>\n<h2>Aper\u00e7u du cours<\/h2>\n<\/div>\n<div>\n<p>Les participants \u00e0 ce cours comprendront les facteurs qui contribuent \u00e0 la d\u00e9t\u00e9rioration de la qualit\u00e9 de l&#8217;eau dans les r\u00e9seaux de distribution. Les cons\u00e9quences involontaires du traitement qui peuvent affecter la stabilit\u00e9 de l&#8217;eau potable dans le r\u00e9seau de distribution seront discut\u00e9es.<\/p>\n<p>Les op\u00e9rateurs comprendront les instabilit\u00e9s microbiologiques, chimiques et physiques qui peuvent se produire dans le syst\u00e8me, comment ces instabilit\u00e9s contribuent \u00e0 la qualit\u00e9 de l&#8217;eau et comment les contr\u00f4ler. Les participants apprendront \u00e9galement \u00e0 \u00e9valuer, hi\u00e9rarchiser et ma\u00eetriser les dangers et les risques sp\u00e9cifiques aux syst\u00e8mes de distribution.<\/p>\n<h2><span style=\"color: revert; font-size: 28.8325px; font-weight: bold; letter-spacing: -0.720813px;\">Public cible<\/span><\/h2>\n<\/div>\n<div>\n<p>Ce cours int\u00e9ressera les op\u00e9rateurs de distribution, nouveaux ou exp\u00e9riment\u00e9s, qui ont un r\u00f4le \u00e0 jouer dans le maintien de la qualit\u00e9 de l&#8217;eau dans leur r\u00e9seau de distribution.<\/p>\n<\/div>\n<h2>M\u00e9thodes de livraison possibles<\/h2>\n<p>Salle de classe, sur place<\/p>\n<\/div>\n<h3><span style=\"font-size: 16px;\">Visitez notre <\/span><a style=\"font-size: 16px;\" href=\"https:\/\/wcwc.ca\/fr\/formation\/cours\/\">page d&#8217;inscription aux cours<\/a><span style=\"font-size: 16px;\">pour conna\u00eetre le calendrier de nos prochains cours! <i class=\"fa fa-calendar\"> <\/i><\/span> <\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Aper\u00e7u du cours Les participants \u00e0 ce cours comprendront les facteurs qui contribuent \u00e0 la d\u00e9t\u00e9rioration de la qualit\u00e9 de l&#8217;eau dans les r\u00e9seaux &#8230;<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[585],"tags":[],"course-type":[],"province":[1031,1039,1034,1037,1016,1041,1035],"class_list":["post-21761","post","type-post","status-publish","format-standard","hentry","category-coursecatalog-fr","province-ab","province-ipe","province-nb","province-ne","province-on","province-sk","province-tnl"],"acf":[],"_links":{"self":[{"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/posts\/21761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/comments?post=21761"}],"version-history":[{"count":7,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/posts\/21761\/revisions"}],"predecessor-version":[{"id":26752,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/posts\/21761\/revisions\/26752"}],"wp:attachment":[{"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/media?parent=21761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/categories?post=21761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/tags?post=21761"},{"taxonomy":"course-type","embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/course-type?post=21761"},{"taxonomy":"province","embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/province?post=21761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}