{"id":21919,"date":"2022-11-22T10:03:43","date_gmt":"2022-11-22T15:03:43","guid":{"rendered":"https:\/\/staging.wcwc.ca\/news-fr\/le-walkerton-clean-water-centre-accueille-de-nouveaux-formateurs-et-developpeurs-de-programmes-detudes\/"},"modified":"2024-01-08T16:02:02","modified_gmt":"2024-01-08T21:02:02","slug":"le-walkerton-clean-water-centre-accueille-de-nouveaux-formateurs-et-developpeurs-de-programmes-detudes","status":"publish","type":"post","link":"https:\/\/wcwc.ca\/fr\/news-fr\/le-walkerton-clean-water-centre-accueille-de-nouveaux-formateurs-et-developpeurs-de-programmes-detudes\/","title":{"rendered":"Le Walkerton Clean Water Centre accueille de nouveaux formateurs et d\u00e9veloppeurs de programmes d&#8217;\u00e9tudes"},"content":{"rendered":"<p>Suite aux accords r\u00e9cemment sign\u00e9s, le Walkerton Clean Water Centre (WCWC) est heureux d&#8217;accueillir dans son \u00e9quipe 40 formateurs contractuels et d\u00e9veloppeurs de programmes d&#8217;\u00e9tudes, dont certains sont nouveaux et d&#8217;autres reviennent.<\/p>\n<figure id=\"attachment_19680\" aria-describedby=\"caption-attachment-19680\" style=\"width: 300px\" class=\"wp-caption alignright\"><a href=\"https:\/\/wcwc.ca\/wp-content\/uploads\/2022\/11\/Honourable-DOConnor-and-BBates.jpg\" data-size=\"2548x1698\" class=\"js-image\"><img decoding=\"async\" data-image-position=\"1\" class=\"size-medium wp-image-19680 fy-content__image\" src=\"https:\/\/wcwc.ca\/wp-content\/uploads\/2022\/11\/Honourable-DOConnor-and-BBates-300x200.jpg\" alt=\"L&#039;honorable Dennis O&#039;Connor, photographi\u00e9 avec le PDG de WCWC, Brian Bates\" width=\"300\" height=\"200\" srcset=\"https:\/\/wcwc.ca\/wp-content\/uploads\/2022\/11\/Honourable-DOConnor-and-BBates-300x200.jpg 300w, https:\/\/wcwc.ca\/wp-content\/uploads\/2022\/11\/Honourable-DOConnor-and-BBates-768x512.jpg 768w, https:\/\/wcwc.ca\/wp-content\/uploads\/2022\/11\/Honourable-DOConnor-and-BBates-1536x1024.jpg 1536w, https:\/\/wcwc.ca\/wp-content\/uploads\/2022\/11\/Honourable-DOConnor-and-BBates-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" fetchpriority=\"high\"><div class=\"fy-image-loading fy-image-loading--spinner\" aria-hidden=\"true\"><\/div><\/a><figcaption id=\"caption-attachment-19680\" class=\"wp-caption-text\">L&#8217;honorable Dennis O&#8217;Connor,<br \/>en photo avec Brian Bates, PDG du WCWC<\/figcaption><\/figure>\n<p>Le 8 novembre 2022, le WCWC a accueilli 29 formateurs et concepteurs de programmes dans ses locaux de Walkerton, en Ontario, pour une journ\u00e9e d&#8217;apprentissage sur les meilleures pratiques en mati\u00e8re d&#8217;\u00e9ducation des adultes, les d\u00e9veloppements dans les m\u00e9thodes de prestation de formation et les nouveaut\u00e9s dans l&#8217;industrie de l&#8217;eau.<\/p>\n<p>Ces professionnels de l&#8217;industrie sont d\u00e9sireux de partager leurs connaissances pour soutenir les op\u00e9rateurs de r\u00e9seaux d&#8217;eau et ont \u00e9t\u00e9 encourag\u00e9s par un message de l&#8217;honorable Dennis O&#8217;Connor, commissaire de la Commission d&#8217;enqu\u00eate de Walkerton, qui a assist\u00e9 \u00e0 l&#8217;\u00e9v\u00e9nement,<\/p>\n<blockquote><p>&#8220;Il est tr\u00e8s impressionnant de voir l&#8217;excellent travail que fait le WCWC pour former ceux qui veillent \u00e0 ce que nos syst\u00e8mes d&#8217;eau potable en Ontario soient s\u00fbrs. F\u00e9licitations pour le prochain cycle de formation des instructeurs et des concepteurs de programmes d&#8217;\u00e9tudes.&#8221;<\/p><\/blockquote>\n<p>Les formateurs et les concepteurs de programmes d&#8217;\u00e9tudes du WCWC apportent leur expertise dans des domaines vari\u00e9s et ont une exp\u00e9rience en tant qu&#8217;ing\u00e9nieurs professionnels, technologues certifi\u00e9s en ing\u00e9nierie, op\u00e9rateurs de traitement et de distribution de l&#8217;eau, inspecteurs de sant\u00e9 publique, techniciens de puits et plombiers. Ces divers talents permettront au WCWC de continuer \u00e0 offrir une formation de la plus haute qualit\u00e9 aux professionnels de l&#8217;eau de tout l&#8217;Ontario.<\/p>\n<p>Pour plus d&#8217;informations sur le WCWC, veuillez visiter <a href=\"http:\/\/www.wcwc.ca\">wcwc.ca<\/a> ou nous contacter au 866-515-0550 ou <a href=\"mailto:inquiry@wcwc.ca\">inquiry@wcwc.ca<\/a>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Suite aux accords r\u00e9cemment sign\u00e9s, le Walkerton Clean Water Centre (WCWC) est heureux d&#8217;accueillir dans son \u00e9quipe 40 formateurs contractuels et d\u00e9veloppeurs de programmes &#8230;<\/p>\n","protected":false},"author":7,"featured_media":19686,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[63,53],"tags":[648,647,649,72,234,64,646],"course-type":[],"province":[],"class_list":["post-21919","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-training-fr","category-news-fr","tag-dennis-oconnor-fr","tag-curriculum-development-fr","tag-trainers-fr","tag-training-fr","tag-classroom-training-fr","tag-drinking-water-training-fr","tag-ceo-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/posts\/21919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/comments?post=21919"}],"version-history":[{"count":1,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/posts\/21919\/revisions"}],"predecessor-version":[{"id":23138,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/posts\/21919\/revisions\/23138"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/media\/19686"}],"wp:attachment":[{"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/media?parent=21919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/categories?post=21919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/tags?post=21919"},{"taxonomy":"course-type","embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/course-type?post=21919"},{"taxonomy":"province","embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/province?post=21919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}