{"id":21921,"date":"2023-11-09T15:44:13","date_gmt":"2023-11-09T20:44:13","guid":{"rendered":"https:\/\/staging.wcwc.ca\/news-fr\/avis-de-recrutement-entretiens-sur-la-voix-du-client-dans-le-cadre-de-la-formation-sur-les-eaux-usees\/"},"modified":"2024-02-22T10:12:43","modified_gmt":"2024-02-22T15:12:43","slug":"avis-de-recrutement-entretiens-sur-la-voix-du-client-dans-le-cadre-de-la-formation-sur-les-eaux-usees","status":"publish","type":"post","link":"https:\/\/wcwc.ca\/fr\/news-fr\/avis-de-recrutement-entretiens-sur-la-voix-du-client-dans-le-cadre-de-la-formation-sur-les-eaux-usees\/","title":{"rendered":"Avis de recrutement : Entretiens sur la voix du client dans le cadre de la formation sur les eaux us\u00e9es"},"content":{"rendered":"\n<p>Le Walkerton Clean Water Centre m\u00e8ne des recherches aupr\u00e8s des exploitants d&#8217;eaux us\u00e9es et des personnes charg\u00e9es de s\u00e9lectionner et d&#8217;autoriser la formation des exploitants afin de d\u00e9terminer les besoins en mati\u00e8re d&#8217;\u00e9laboration et de prestation de cours et d&#8217;am\u00e9liorer les possibilit\u00e9s de formation continue dans la province de l&#8217;Ontario. Ces entretiens individuels en personne ou virtuels dureront environ 30 \u00e0 45 minutes et le temps de participation sera r\u00e9compens\u00e9 par une carte-cadeau Amazon de 25 dollars. Vos commentaires nous aideront \u00e0 \u00e9laborer les futurs cours de formation et nous permettront de contribuer au d\u00e9veloppement professionnel des op\u00e9rateurs de traitement des eaux us\u00e9es dans la province de l&#8217;Ontario, en fonction des besoins et des demandes de l&#8217;industrie. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Walkerton Clean Water Centre m\u00e8ne des recherches aupr\u00e8s des exploitants d&#8217;eaux us\u00e9es et des personnes charg\u00e9es de s\u00e9lectionner et d&#8217;autoriser la formation des &#8230;<\/p>\n","protected":false},"author":7,"featured_media":6645,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[53],"tags":[],"course-type":[],"province":[],"class_list":["post-21921","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/posts\/21921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/comments?post=21921"}],"version-history":[{"count":2,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/posts\/21921\/revisions"}],"predecessor-version":[{"id":23972,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/posts\/21921\/revisions\/23972"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/media\/6645"}],"wp:attachment":[{"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/media?parent=21921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/categories?post=21921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/tags?post=21921"},{"taxonomy":"course-type","embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/course-type?post=21921"},{"taxonomy":"province","embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/province?post=21921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}