{"id":24861,"date":"2025-03-03T15:48:31","date_gmt":"2025-03-03T20:48:31","guid":{"rendered":"https:\/\/wcwc.ca\/news-fr\/registration-now-open-for-maintenancefest-3\/"},"modified":"2025-03-05T09:13:43","modified_gmt":"2025-03-05T14:13:43","slug":"registration-now-open-for-maintenancefest-3","status":"publish","type":"post","link":"https:\/\/wcwc.ca\/fr\/news-fr\/registration-now-open-for-maintenancefest-3\/","title":{"rendered":"LES INSCRIPTIONS SONT OUVERTES POUR LA MAINTENANCEFEST"},"content":{"rendered":"\n<p>Le Centre de Walkerton pour l\u2019assainissement de l\u2019eau (CWAE) est heureux d\u2019annoncer que Maintenancefest aura lieu \u00e0 quatre endroits diff\u00e9rents en Ontario cette ann\u00e9e.<\/p>\n\n\n\n<p>Maintenancefest est un \u00e9v\u00e9nement unique de formation pratique qui permet aux op\u00e9rateurs de r\u00e9seaux d&#8217;eau potable de suivre les modules de formation de leur choix et d&#8217;obtenir jusqu&#8217;\u00e0 1,2 CEU. Voici les modules pr\u00e9vus :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00c9l\u00e9ments de base de la localisation de services publics<\/li>\n\n\n\n<li>Pompes centrifuges<\/li>\n\n\n\n<li>\u00c9quipement de dosage chimique<\/li>\n\n\n\n<li>Surveillance continue du chlore libre<\/li>\n\n\n\n<li>Essai de pression hydrostatique<\/li>\n\n\n\n<li>Fer et mangan\u00e8se dans les eaux souterraines<\/li>\n\n\n\n<li>Essai de floculation<\/li>\n\n\n\n<li>D\u00e9tection des fuites<\/li>\n\n\n\n<li>Entretien des vannes<\/li>\n\n\n\n<li>Soupapes de r\u00e9glage de pression<\/li>\n\n\n\n<li>Exigences en mati\u00e8re de tenue de documents<\/li>\n\n\n\n<li>Rin\u00e7age unidirectionnel<\/li>\n\n\n\n<li>Th\u00e9orie et maintenance de la d\u00e9sinfection par UV<\/li>\n\n\n\n<li>Sensibilisation aux compteurs d&#8217;eau<\/li>\n\n\n\n<li>Piquage de la conduite principale<\/li>\n<\/ul>\n\n\n\n<p>Rejoignez-nous \u00e0 l\u2019heure et \u00e0 l&#8217;endroit qui vous conviennent le mieux :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le 5 juin 2025 \u00e0 Rama, Ontario<\/li>\n\n\n\n<li>Les 25 et 26 juin 2025 \u00e0 Kenora, Ontario<\/li>\n\n\n\n<li>Les 26 et 27 ao\u00fbt 2025 \u00e0 Walkerton, Ontario<\/li>\n\n\n\n<li>Les 10 et 11 septembre 2025 \u00e0 Kingston, Ontario<\/li>\n<\/ul>\n\n\n\n<p>Le nombre de places est limit\u00e9, alors inscrivez-vous d\u00e8s aujourd&#8217;hui \u00e0 <a href=\"mailto:wcwc.ca\/registration\">wcwc.ca\/registration<\/a>, ou contactez-nous au 866-515-0550 ou <a href=\"mailto:training@wcwc.ca\">training@wcwc.ca<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Centre de Walkerton pour l\u2019assainissement de l\u2019eau (CWAE) est heureux d\u2019annoncer que Maintenancefest aura lieu \u00e0 quatre endroits diff\u00e9rents en Ontario cette ann\u00e9e. &#8230;<\/p>\n","protected":false},"author":7,"featured_media":24877,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[63,663,53],"tags":[],"course-type":[],"province":[],"class_list":["post-24861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-training-fr","category-fete-de-la-maintenance","category-news-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/posts\/24861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/comments?post=24861"}],"version-history":[{"count":3,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/posts\/24861\/revisions"}],"predecessor-version":[{"id":24864,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/posts\/24861\/revisions\/24864"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/media\/24877"}],"wp:attachment":[{"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/media?parent=24861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/categories?post=24861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/tags?post=24861"},{"taxonomy":"course-type","embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/course-type?post=24861"},{"taxonomy":"province","embeddable":true,"href":"https:\/\/wcwc.ca\/fr\/wp-json\/wp\/v2\/province?post=24861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}